{"id":1037,"date":"2024-07-26T20:00:21","date_gmt":"2024-07-26T20:00:21","guid":{"rendered":"https:\/\/wp-staging.futureofnews.com\/index.php\/membership-login\/password-reset\/"},"modified":"2024-07-26T20:00:21","modified_gmt":"2024-07-26T20:00:21","slug":"password-reset","status":"publish","type":"page","link":"https:\/\/wp-staging.futureofnews.com\/index.php\/membership-login\/password-reset\/","title":{"rendered":"Password Reset"},"content":{"rendered":"<div class=\"swpm-pw-reset-widget-form\">\n    <form id=\"swpm-pw-reset-form\" name=\"swpm-reset-form\" method=\"post\" action=\"\">\n        <div class=\"swpm-pw-reset-widget-inside\">\n            <div class=\"swpm-pw-reset-email swpm-margin-top-10\">\n                <label for=\"swpm_reset_email\" class=\"swpm_label swpm-pw-reset-email-label\">Email Address<\/label>\n            <\/div>\n            <div class=\"swpm-pw-reset-email-input swpm-margin-top-10\">\n                <input type=\"text\" name=\"swpm_reset_email\" class=\"swpm-text-field swpm-pw-reset-text\" id=\"swpm_reset_email\"  value=\"\" size=\"30\" \/>\n            <\/div>\n            <div class=\"swpm-before-login-submit-section\"><\/div>\n            <div class=\"swpm-pw-reset-submit-button\">\n                <input type=\"submit\" name=\"swpm-reset\" class=\"swpm-pw-reset-submit swpm-submit-btn-default-style\" value=\"Reset Password\" \/>\n            <\/div>\n        <\/div>\n    <\/form>\n<\/div>\n<div class=\"swpm_pass_reset_processing_msg_section\">\n    <p id=\"swpm_pass_reset_processing_msg\" hidden=\"hidden\">\n        Processing password reset request...    <\/p>\n<\/div>\n<script>\n  document.getElementById(\"swpm-pw-reset-form\").addEventListener(\"submit\", function() {\n  let p = document.getElementById('swpm_pass_reset_processing_msg');\n    p.removeAttribute(\"hidden\");\n  });\n<\/script>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":1023,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"class_list":["post-1037","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/wp-staging.futureofnews.com\/index.php\/wp-json\/wp\/v2\/pages\/1037","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp-staging.futureofnews.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/wp-staging.futureofnews.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/wp-staging.futureofnews.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wp-staging.futureofnews.com\/index.php\/wp-json\/wp\/v2\/comments?post=1037"}],"version-history":[{"count":0,"href":"https:\/\/wp-staging.futureofnews.com\/index.php\/wp-json\/wp\/v2\/pages\/1037\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/wp-staging.futureofnews.com\/index.php\/wp-json\/wp\/v2\/pages\/1023"}],"wp:attachment":[{"href":"https:\/\/wp-staging.futureofnews.com\/index.php\/wp-json\/wp\/v2\/media?parent=1037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}