{"id":1016,"date":"2024-07-26T20:00:21","date_gmt":"2024-07-26T20:00:21","guid":{"rendered":"https:\/\/wp-staging.futureofnews.com\/index.php\/membership-join\/membership-registration\/"},"modified":"2024-07-26T20:00:21","modified_gmt":"2024-07-26T20:00:21","slug":"membership-registration","status":"publish","type":"page","link":"https:\/\/wp-staging.futureofnews.com\/index.php\/membership-join\/membership-registration\/","title":{"rendered":"Registration"},"content":{"rendered":"<div class=\"swpm-registration-widget-form\">\n    <form id=\"swpm-registration-form\" class=\"swpm-form\" name=\"swpm-registration-form\" method=\"post\" action=\"\">\n        <input type=\"hidden\" name=\"level_identifier\" value=\"c9f0f895fb98ab9159f51fd0297e236d\" \/>\n        <div class=\"swpm-registration-form-section\">\n            <div class=\"swpm-form-row swpm-username-row\" >\n                <div class=\"swpm-form-label-wrap swpm-form-username-label-wrap\">\n                    <label for=\"user_name\">Username<\/label>\n                <\/div>\n                <div class=\"swpm-form-input-wrap swpm-form-username-input-wrap\">\n                    <input type=\"text\" id=\"user_name\" autocomplete=\"new-username\" class=\"swpm-form-field swpm-form-username\" value=\"\" name=\"user_name\"  \/>\n                <\/div>\n                <div class=\"swpm-form-desc\"><\/div>\n            <\/div>\n            <div class=\"swpm-form-row swpm-email-row\">\n                <div class=\"swpm-form-label-wrap swpm-form-email-label-wrap\">\n                    <label for=\"email\">Email<\/label>\n                <\/div>\n                <div class=\"swpm-form-input-wrap swpm-form-email-input-wrap\">\n                    <input type=\"text\" autocomplete=\"off\" id=\"email\" class=\"swpm-form-field swpm-form-email\" value=\"\" name=\"email\" \/>\n                <\/div>\n                <div class=\"swpm-form-desc\"><\/div>\n            <\/div>\n            <div class=\"swpm-form-row swpm-password-row\">\n                <div class=\"swpm-form-label-wrap swpm-form-password-label-wrap\">\n                    <label for=\"password\">Password<\/label>\n                <\/div>\n                <div class=\"swpm-form-input-wrap swpm-form-password-input-wrap\">\n                    <input type=\"password\" autocomplete=\"new-password\" id=\"password\" class=\"swpm-form-field swpm-form-password\" value=\"\" name=\"password\" \/>\n                <\/div>\n                <div class=\"swpm-form-desc\"><\/div>\n            <\/div>\n            <div class=\"swpm-form-row swpm-repass-row\">\n                <div class=\"swpm-form-label-wrap swpm-form-repass-label-wrap\">\n                    <label for=\"password_re\">Repeat Password<\/label>\n                <\/div>\n                <div class=\"swpm-form-input-wrap swpm-form-repass-input-wrap\">\n                    <input type=\"password\" autocomplete=\"new-password\" id=\"password_re\" class=\"swpm-form-field swpm-form-repass\" value=\"\" name=\"password_re\" \/>\n                <\/div>\n                <div class=\"swpm-form-desc\"><\/div>\n            <\/div>\n            <div class=\"swpm-form-row swpm-firstname-row\" >\n                <div class=\"swpm-form-label-wrap swpm-form-firstname-label-wrap\">\n                    <label for=\"first_name\">First Name<\/label>\n                <\/div>\n                <div class=\"swpm-form-input-wrap swpm-form-firstname-input-wrap\">\n                    <input type=\"text\" id=\"first_name\" class=\"swpm-form-field swpm-form-firstname\" value=\"\" name=\"first_name\" \/>\n                <\/div>\n                <div class=\"swpm-form-desc\"><\/div>\n            <\/div>\n            <div class=\"swpm-form-row swpm-lastname-row\" >\n                <div class=\"swpm-form-label-wrap swpm-form-lastname-label-wrap\">\n                    <label for=\"last_name\">Last Name<\/label>\n                <\/div>\n                <div class=\"swpm-form-input-wrap swpm-form-lastname-input-wrap\">\n                    <input type=\"text\" id=\"last_name\" class=\"swpm-form-field swpm-form-lastname\" value=\"\" name=\"last_name\" \/>\n                <\/div>\n                <div class=\"swpm-form-desc\"><\/div>\n            <\/div>\n            <div\n                class=\"swpm-form-row swpm-membership-level-row\"\n                                style=\"\"\n            >\n                <div class=\"swpm-form-label-wrap swpm-form-membership-level-label-wrap\">\n                    <label for=\"membership_level\">Membership Level<\/label>\n                <\/div>\n                <div class=\"swpm-form-membership-level-value\">\n                    Community Membership (Free)<input type=\"hidden\" value=\"8\" size=\"50\" name=\"swpm_membership_level\" id=\"membership_level\" \/><input type=\"hidden\" name=\"swpm_level_hash\" value=\"83e986326a8665285acbf48f995d7f61\" \/>                <\/div>\n            <\/div>\n            \n                        <div class=\"swpm-before-registration-submit-section\" align=\"center\"><\/div>\n\n            <div class=\"swpm-form-row swpm-submit-section swpm-registration-submit-section\">\n                <button type=\"submit\" class=\"swpm-submit swpm-registration-submit-button swpm-submit-btn-default-style\">Register<\/button>\n                <input type=\"hidden\" name=\"swpm_registration_submit\" value=\"Register\">\n            <\/div>\n        <\/div>\n\n        <input type=\"hidden\" name=\"action\" value=\"custom_posts\" \/>\n    <\/form>\n\n    <style>\n        .swpm-registration-submit-section{\n            text-align: center;\n        }\n        .swpm-form .swpm-form-row {\n            margin-bottom: 0.8rem;\n        }\n\n        .swpm-form .swpm-submit-section {\n            margin-top: 1rem;\n        }\n\n        .swpm-form .swpm-form-row.error .swpm-form-field {\n            border-color: #cc0000 !important;\n            outline-color: #cc0000 !important;\n        }\n\n        .swpm-form .swpm-form-row.error .swpm-form-desc {\n            color: #cc0000 !important;\n            font-size: smaller !important;\n        }\n\n        .swpm-form .swpm-form-row.error .swpm-form-desc>ul {\n            list-style: none !important;\n            padding: 0 !important;\n            margin: 4px 0 0 !important;\n        }\n    <\/style>\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":1009,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"class_list":["post-1016","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/wp-staging.futureofnews.com\/index.php\/wp-json\/wp\/v2\/pages\/1016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp-staging.futureofnews.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/wp-staging.futureofnews.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/wp-staging.futureofnews.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wp-staging.futureofnews.com\/index.php\/wp-json\/wp\/v2\/comments?post=1016"}],"version-history":[{"count":0,"href":"https:\/\/wp-staging.futureofnews.com\/index.php\/wp-json\/wp\/v2\/pages\/1016\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/wp-staging.futureofnews.com\/index.php\/wp-json\/wp\/v2\/pages\/1009"}],"wp:attachment":[{"href":"https:\/\/wp-staging.futureofnews.com\/index.php\/wp-json\/wp\/v2\/media?parent=1016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}